{"id":26610,"date":"2022-08-10T16:51:26","date_gmt":"2022-08-10T13:51:26","guid":{"rendered":"https:\/\/mawelodges.com\/?p=26610"},"modified":"2026-05-13T15:11:57","modified_gmt":"2026-05-13T12:11:57","slug":"mto-wa-mbu","status":"publish","type":"post","link":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/","title":{"rendered":"Village de Mto wa Mbu : la richesse de la culture et de la nature"},"content":{"rendered":"\n<p>Le village de Mto wa Mbu se trouve pr\u00e8s de la vall\u00e9e du Grand Rift en Tanzanie. Le village de Mto wa Mbu est un joyau cach\u00e9 qui offre un m\u00e9lange unique de diversit\u00e9 culturelle et de beaut\u00e9 naturelle. De ses march\u00e9s locaux anim\u00e9s aux paysages luxuriants et \u00e0 la faune diversifi\u00e9e, Mto wa Mbu est un lieu o\u00f9 les visiteurs peuvent d\u00e9couvrir l&rsquo;essence de la Tanzanie en une seule destination. Dans cet article, nous explorerons le charme du village de Mto wa Mbu et ses tr\u00e9sors.    <\/p>\n\n<h2 class=\"wp-block-heading\">Mosa\u00efque culturelle<\/h2>\n\n<p>L&rsquo;une des caract\u00e9ristiques les plus remarquables de Mto wa Mbu est sa population dynamique et diversifi\u00e9e. Plus de 120 tribus coexistent dans ce petit village, ce qui en fait un microcosme de la richesse culturelle de la Tanzanie. De plus, en vous promenant dans les rues, vous rencontrerez les sourires chaleureux des Chagga, des Sukuma et des Maasa\u00ef, parmi tant d&rsquo;autres. \u00c9changer avec les habitants offre une occasion rare d&rsquo;avoir un aper\u00e7u de leur mode de vie, de leurs traditions et de leurs coutumes.   <\/p>\n\n<h2 class=\"wp-block-heading\">March\u00e9s locaux du village de Mto wa Mbu<\/h2>\n\n<p>Les march\u00e9s color\u00e9s du village refl\u00e8tent v\u00e9ritablement sa composition multiculturelle. Sur les march\u00e9s, vous trouverez une vari\u00e9t\u00e9 de produits, allant des bijoux artisanaux et des v\u00eatements traditionnels aux produits frais et aux \u00e9pices. L&rsquo;atmosph\u00e8re anim\u00e9e est \u00e9galement un r\u00e9gal pour les sens, avec les ar\u00f4mes des plats locaux qui flottent dans l&rsquo;air tandis que vous \u00e9changez avec des vendeurs accueillants.  <\/p>\n\n<h2 class=\"wp-block-heading\">Aventures gastronomiques<\/h2>\n\n<p>La sc\u00e8ne culinaire de Mto wa Mbu est une d\u00e9licieuse fusion de saveurs inspir\u00e9es par sa population multiculturelle. Les visiteurs peuvent savourer des plats tanzaniens traditionnels comme le nyama choma (viande grill\u00e9e) et l&rsquo;ugali (bouillie de ma\u00efs) aux c\u00f4t\u00e9s de plats influenc\u00e9s par des cuisines internationales. Cependant, partager un repas avec les habitants \u00e9veille les papilles et offre un aper\u00e7u de l&rsquo;\u00e9change culturel qui d\u00e9finit ce village.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto-wa-mbu-1024x682.webp\" alt=\"\" class=\"wp-image-19601\" srcset=\"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto-wa-mbu-1024x682.webp 1024w, https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto-wa-mbu-300x200.webp 300w, https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto-wa-mbu-768x512.webp 768w, https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto-wa-mbu.webp 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">V\u00e9lo et promenades dans la nature<\/h2>\n\n<p>Les amoureux de la nature trouveront beaucoup \u00e0 explorer dans les environnements luxuriants de Mto wa Mbu. Participez \u00e0 une excursion guid\u00e9e \u00e0 v\u00e9lo \u00e0 travers les plantations de bananes, les rizi\u00e8res et les villages locaux. L&rsquo;exp\u00e9rience vous permet d&rsquo;interagir avec les agriculteurs et d&rsquo;observer leurs pratiques agricoles de premi\u00e8re main. Pour ceux qui pr\u00e9f\u00e8rent un rythme plus lent, les promenades dans la nature le long des rives du lac Manyara offrent des aper\u00e7us de la diversit\u00e9 de l&rsquo;avifaune et de la faune.   <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto_Wa_Wa_Mbu-1024x682.webp\" alt=\"\" class=\"wp-image-19602\" srcset=\"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto_Wa_Wa_Mbu-1024x682.webp 1024w, https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto_Wa_Wa_Mbu-300x200.webp 300w, https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto_Wa_Wa_Mbu-768x512.webp 768w, https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/08\/Mto_Wa_Wa_Mbu.webp 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>\u00a0<\/p>\n\n<h2 class=\"wp-block-heading\">Parc national du lac Manyara<\/h2>\n\n<p>Cette ville est la porte d&rsquo;entr\u00e9e du parc national du lac Manyara, connu pour ses \u00e9cosyst\u00e8mes diversifi\u00e9s et sa faune. Le parc abrite des lions grimpeurs d&rsquo;arbres, des troupeaux d&rsquo;\u00e9l\u00e9phants et une impressionnante vari\u00e9t\u00e9 d&rsquo;esp\u00e8ces d&rsquo;oiseaux. Un safari dans le parc promet des rencontres extraordinaires avec la nature dans son \u00e9tat le plus pur.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-let-s-explore\">Explorons ensemble<\/h2>\n\n<p>Le village de Mto wa Mbu t\u00e9moigne de la coexistence harmonieuse de la nature et de la culture. Sa diversit\u00e9 culturelle et sa proximit\u00e9 avec le parc national de Manyara en font une destination pour vivre une v\u00e9ritable exp\u00e9rience tanzanienne.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le village de Mto wa Mbu se trouve pr\u00e8s de la vall\u00e9e du Grand Rift en Tanzanie. Le village de Mto wa Mbu est un joyau cach\u00e9 qui offre un m\u00e9lange unique de diversit\u00e9 culturelle et de beaut\u00e9 naturelle. De ses march\u00e9s locaux anim\u00e9s aux paysages luxuriants et \u00e0 la faune diversifi\u00e9e, Mto wa Mbu&#8230;<\/p>\n","protected":false},"author":1,"featured_media":26611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[512],"tags":[],"class_list":["post-26610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destinations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Village de Mto wa Mbu : la richesse de la culture et de la nature - Mawe Lodges<\/title>\n<meta name=\"description\" content=\"Le village de Mto wa Mbu est une petite ville culturellement dynamique situ\u00e9e \u00e0 proximit\u00e9 du parc national du lac Manyara, offrant de formidables interactions culturelles avec les habitants\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Village de Mto wa Mbu : la richesse de la culture et de la nature\" \/>\n<meta property=\"og:description\" content=\"Le village de Mto wa Mbu est une petite ville culturellement dynamique situ\u00e9e \u00e0 proximit\u00e9 du parc national du lac Manyara, offrant de formidables interactions culturelles avec les habitants\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/\" \/>\n<meta property=\"og:site_name\" content=\"Mawe Lodges\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Mawe-Lodges\/100066949615500\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-10T13:51:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:11:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/person\\\/3dfe00c0df5a7702e1d858a793499af4\"},\"headline\":\"Village de Mto wa Mbu : la richesse de la culture et de la nature\",\"datePublished\":\"2022-08-10T13:51:26+00:00\",\"dateModified\":\"2026-05-13T12:11:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/\"},\"wordCount\":577,\"publisher\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mto-wa-mbu-village.webp\",\"articleSection\":[\"Destinations\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/\",\"name\":\"Village de Mto wa Mbu : la richesse de la culture et de la nature - Mawe Lodges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mto-wa-mbu-village.webp\",\"datePublished\":\"2022-08-10T13:51:26+00:00\",\"dateModified\":\"2026-05-13T12:11:57+00:00\",\"description\":\"Le village de Mto wa Mbu est une petite ville culturellement dynamique situ\u00e9e \u00e0 proximit\u00e9 du parc national du lac Manyara, offrant de formidables interactions culturelles avec les habitants\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mto-wa-mbu-village.webp\",\"contentUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mto-wa-mbu-village.webp\",\"width\":1400,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/mto-wa-mbu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Village de Mto wa Mbu : la richesse de la culture et de la nature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/\",\"name\":\"Mawe Lodges\",\"description\":\"Mawe Lodges official website\",\"publisher\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#organization\",\"name\":\"Mawe Lodges\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-Mawe-logo-3-300x117-1.png\",\"contentUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-Mawe-logo-3-300x117-1.png\",\"width\":300,\"height\":117,\"caption\":\"Mawe Lodges\"},\"image\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Mawe-Lodges\\\/100066949615500\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mawelodges\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/person\\\/3dfe00c0df5a7702e1d858a793499af4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/mawelodges.com\"],\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Village de Mto wa Mbu : la richesse de la culture et de la nature - Mawe Lodges","description":"Le village de Mto wa Mbu est une petite ville culturellement dynamique situ\u00e9e \u00e0 proximit\u00e9 du parc national du lac Manyara, offrant de formidables interactions culturelles avec les habitants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/","og_locale":"fr_FR","og_type":"article","og_title":"Village de Mto wa Mbu : la richesse de la culture et de la nature","og_description":"Le village de Mto wa Mbu est une petite ville culturellement dynamique situ\u00e9e \u00e0 proximit\u00e9 du parc national du lac Manyara, offrant de formidables interactions culturelles avec les habitants","og_url":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/","og_site_name":"Mawe Lodges","article_publisher":"https:\/\/www.facebook.com\/people\/Mawe-Lodges\/100066949615500\/","article_published_time":"2022-08-10T13:51:26+00:00","article_modified_time":"2026-05-13T12:11:57+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/#article","isPartOf":{"@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/"},"author":{"name":"admin","@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/person\/3dfe00c0df5a7702e1d858a793499af4"},"headline":"Village de Mto wa Mbu : la richesse de la culture et de la nature","datePublished":"2022-08-10T13:51:26+00:00","dateModified":"2026-05-13T12:11:57+00:00","mainEntityOfPage":{"@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/"},"wordCount":577,"publisher":{"@id":"https:\/\/mawelodges.com\/fr\/#organization"},"image":{"@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/#primaryimage"},"thumbnailUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp","articleSection":["Destinations"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/","url":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/","name":"Village de Mto wa Mbu : la richesse de la culture et de la nature - Mawe Lodges","isPartOf":{"@id":"https:\/\/mawelodges.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/#primaryimage"},"image":{"@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/#primaryimage"},"thumbnailUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp","datePublished":"2022-08-10T13:51:26+00:00","dateModified":"2026-05-13T12:11:57+00:00","description":"Le village de Mto wa Mbu est une petite ville culturellement dynamique situ\u00e9e \u00e0 proximit\u00e9 du parc national du lac Manyara, offrant de formidables interactions culturelles avec les habitants","breadcrumb":{"@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/#primaryimage","url":"https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp","contentUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp","width":1400,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/mawelodges.com\/fr\/mto-wa-mbu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mawelodges.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Village de Mto wa Mbu : la richesse de la culture et de la nature"}]},{"@type":"WebSite","@id":"https:\/\/mawelodges.com\/fr\/#website","url":"https:\/\/mawelodges.com\/fr\/","name":"Mawe Lodges","description":"Mawe Lodges official website","publisher":{"@id":"https:\/\/mawelodges.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mawelodges.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mawelodges.com\/fr\/#organization","name":"Mawe Lodges","url":"https:\/\/mawelodges.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-Mawe-logo-3-300x117-1.png","contentUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-Mawe-logo-3-300x117-1.png","width":300,"height":117,"caption":"Mawe Lodges"},"image":{"@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Mawe-Lodges\/100066949615500\/","https:\/\/www.instagram.com\/mawelodges\/"]},{"@type":"Person","@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/person\/3dfe00c0df5a7702e1d858a793499af4","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/mawelodges.com"],"url":"https:\/\/mawelodges.com\/fr\/author\/admin\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp",1400,933,false],"thumbnail":["https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village-150x150.webp",150,150,true],"medium":["https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village-300x200.webp",300,200,true],"medium_large":["https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village-768x512.webp",768,512,true],"large":["https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village-1024x682.webp",1024,682,true],"1536x1536":["https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp",1400,933,false],"2048x2048":["https:\/\/mawelodges.com\/wp-content\/uploads\/2022\/08\/Mto-wa-mbu-village.webp",1400,933,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/mawelodges.com\/fr\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Le village de Mto wa Mbu se trouve pr\u00e8s de la vall\u00e9e du Grand Rift en Tanzanie. Le village de Mto wa Mbu est un joyau cach\u00e9 qui offre un m\u00e9lange unique de diversit\u00e9 culturelle et de beaut\u00e9 naturelle. De ses march\u00e9s locaux anim\u00e9s aux paysages luxuriants et \u00e0 la faune diversifi\u00e9e, Mto wa Mbu...","_links":{"self":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts\/26610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/comments?post=26610"}],"version-history":[{"count":4,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts\/26610\/revisions"}],"predecessor-version":[{"id":28880,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts\/26610\/revisions\/28880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/media\/26611"}],"wp:attachment":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/media?parent=26610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/categories?post=26610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/tags?post=26610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}