{"id":26957,"date":"2023-03-03T08:08:43","date_gmt":"2023-03-03T05:08:43","guid":{"rendered":"https:\/\/mawelodges.com\/?p=26957"},"modified":"2026-05-13T14:56:30","modified_gmt":"2026-05-13T11:56:30","slug":"african-wild-dogs-in-tarangire","status":"publish","type":"post","link":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/","title":{"rendered":"Lycaons dans le parc national de Tarangire"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-african-wild-dogs-in-tarangire-national-park-the-hidden-gem-of-tanzania-s-wildlife\">Lycaons dans le parc national de Tarangire : le joyau cach\u00e9 de la faune tanzanienne<\/h2>\n\n<h2 class=\"wp-block-heading\">D\u00e9couvrez les lycaons \u00e0 Tarangire<\/h2>\n\n<p>Le parc national de Tarangire est un joyau cach\u00e9, r\u00e9put\u00e9 pour sa faune vari\u00e9e et abondante, au c\u0153ur du circuit safari du nord de la Tanzanie. Parmi les habitants embl\u00e9matiques du parc, le lycaon africain, \u00e9galement appel\u00e9 \u00ab chien peint \u00bb, se distingue comme un symbole de la biodiversit\u00e9 du parc et des efforts de conservation. Cet article de blog vous emm\u00e8ne \u00e0 la d\u00e9couverte du monde fascinant des lycaons \u00e0 Tarangire.  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Parc national de Tarangire : un sanctuaire pour la faune<\/strong><\/h2>\n\n<p>Le parc national de Tarangire, souvent \u00e9clips\u00e9 par ses c\u00e9l\u00e8bres voisins comme le Serengeti et le crat\u00e8re du Ngorongoro, offre une exp\u00e9rience de safari unique et moins fr\u00e9quent\u00e9e. Le parc est r\u00e9put\u00e9 pour ses majestueux baobabs, ses paysages pittoresques et la rivi\u00e8re Tarangire, v\u00e9ritable source de vie pour sa faune diversifi\u00e9e. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00c0 la rencontre des canid\u00e9s peints<\/strong><\/h2>\n\n<p>Les lycaons sont une esp\u00e8ce fortement menac\u00e9e, ce qui en fait une observation rare dans de nombreux parcs africains. Toutefois, le parc national de Tarangire figure parmi les meilleurs endroits pour apercevoir ces pr\u00e9dateurs discrets. Connus pour leurs motifs de pelage saisissants, semblables \u00e0 une toile de peintre, les lycaons pr\u00e9sentent une dynamique sociale fascinante au sein de leurs meutes.  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Pourquoi Tarangire est un haut lieu d\u2019observation des lycaons<\/strong><\/h2>\n\n<ol class=\"wp-block-list\">\n<li><strong>Proies abondantes<\/strong> : l\u2019\u00e9cosyst\u00e8me diversifi\u00e9 de Tarangire abrite de nombreuses esp\u00e8ces de proies, notamment des impalas, des gazelles et des dik-diks, qui attirent les lycaons en qu\u00eate de nourriture.<\/li>\n\n\n\n<li><strong>Vastes territoires<\/strong> : les lycaons ont besoin de grands domaines vitaux, et l\u2019immensit\u00e9 sauvage de Tarangire leur offre l\u2019espace n\u00e9cessaire pour prosp\u00e9rer.<\/li>\n\n\n\n<li><strong>Efforts de conservation<\/strong> : les autorit\u00e9s du parc et les organisations de conservation \u0153uvrent avec diligence pour prot\u00e9ger et suivre la population de lycaons, afin d\u2019assurer leur survie dans le parc.<\/li>\n<\/ol>\n\n<p><strong>Le frisson d\u2019une observation de lycaons<\/strong><\/p>\n\n<p>De plus, observer des lycaons \u00e0 Tarangire est une exp\u00e9rience palpitante et inoubliable pour les passionn\u00e9s de safari. Leur comportement en meute, qui inclut la chasse coop\u00e9rative et de forts liens sociaux, est un spectacle impressionnant. Les voir dans la nature offre une occasion unique d\u2019assister \u00e0 leurs interactions complexes et \u00e0 leur remarquable efficacit\u00e9 \u00e0 la chasse.  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>D\u00e9fis et initiatives de conservation<\/strong><\/h2>\n\n<p>Cependant, malgr\u00e9 l\u2019importance de Tarangire comme refuge pour les lycaons, ceux-ci font face \u00e0 diverses menaces, notamment la perte d\u2019habitat et les conflits entre l\u2019homme et la faune. Des organisations de conservation telles que l\u2019African Wildlife Foundation et le Tanzania Wildlife Research Institute m\u00e8nent des recherches et des actions de conservation pour prot\u00e9ger ces canid\u00e9s menac\u00e9s. <\/p>\n\n<p><strong>Conseils pour un safari lycaons r\u00e9ussi \u00e0 Tarangire<\/strong><\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>P\u00e9riode<\/strong> : la saison s\u00e8che (de juin \u00e0 octobre) est la meilleure p\u00e9riode pour observer la faune \u00e0 Tarangire, y compris les lycaons.<\/li>\n\n\n\n<li><strong>Safaris guid\u00e9s<\/strong> : envisagez de participer \u00e0 un safari guid\u00e9 avec des rangers exp\u00e9riment\u00e9s, familiers des meilleurs sites d\u2019observation de la faune du parc.<\/li>\n\n\n\n<li><strong>Patience<\/strong> : les lycaons sont connus pour leur impr\u00e9visibilit\u00e9 ; la patience est donc essentielle lorsque vous attendez une observation.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\"><strong>Suivre les lycaons <\/strong>\u00e0 Tarangire.<\/h2>\n\n<p>Enfin, le statut du parc national de Tarangire en tant que sanctuaire pour les lycaons met en lumi\u00e8re l\u2019importance de pr\u00e9server les \u00e9cosyst\u00e8mes uniques de la Tanzanie. Lors de la pr\u00e9paration de votre safari en Tanzanie, pensez \u00e0 inclure Tarangire dans votre itin\u00e9raire afin d\u2019observer ces canid\u00e9s charismatiques et menac\u00e9s dans leur habitat naturel.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lycaons dans le parc national de Tarangire : le joyau cach\u00e9 de la faune tanzanienne D\u00e9couvrez les lycaons \u00e0 Tarangire Le parc national de Tarangire est un joyau cach\u00e9, r\u00e9put\u00e9 pour sa faune vari\u00e9e et abondante, au c\u0153ur du circuit safari du nord de la Tanzanie. Parmi les habitants embl\u00e9matiques du parc, le lycaon africain,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":26958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[512,514],"tags":[],"class_list":["post-26957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destinations","category-experiences-et-activites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lycaons dans le parc national de Tarangire - Mawe Lodges<\/title>\n<meta name=\"description\" content=\"Un safari en Tanzanie vous permet d\u2019observer les lycaons \u00e0 Tarangire, o\u00f9 ils sont pr\u00e9sents. Les lycaons vivent toujours en meutes pouvant compter jusqu\u2019\u00e0 60 individus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lycaons dans le parc national de Tarangire\" \/>\n<meta property=\"og:description\" content=\"Un safari en Tanzanie vous permet d\u2019observer les lycaons \u00e0 Tarangire, o\u00f9 ils sont pr\u00e9sents. Les lycaons vivent toujours en meutes pouvant compter jusqu\u2019\u00e0 60 individus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/\" \/>\n<meta property=\"og:site_name\" content=\"Mawe Lodges\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Mawe-Lodges\/100066949615500\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T05:08:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T11:56:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/person\\\/3dfe00c0df5a7702e1d858a793499af4\"},\"headline\":\"Lycaons dans le parc national de Tarangire\",\"datePublished\":\"2023-03-03T05:08:43+00:00\",\"dateModified\":\"2026-05-13T11:56:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/wild-dogs-in-tarangire.webp\",\"articleSection\":[\"Destinations\",\"Exp\u00e9riences et activit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/\",\"name\":\"Lycaons dans le parc national de Tarangire - Mawe Lodges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/wild-dogs-in-tarangire.webp\",\"datePublished\":\"2023-03-03T05:08:43+00:00\",\"dateModified\":\"2026-05-13T11:56:30+00:00\",\"description\":\"Un safari en Tanzanie vous permet d\u2019observer les lycaons \u00e0 Tarangire, o\u00f9 ils sont pr\u00e9sents. Les lycaons vivent toujours en meutes pouvant compter jusqu\u2019\u00e0 60 individus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/wild-dogs-in-tarangire.webp\",\"contentUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/wild-dogs-in-tarangire.webp\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/african-wild-dogs-in-tarangire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lycaons dans le parc national de Tarangire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/\",\"name\":\"Mawe Lodges\",\"description\":\"Mawe Lodges official website\",\"publisher\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#organization\",\"name\":\"Mawe Lodges\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-Mawe-logo-3-300x117-1.png\",\"contentUrl\":\"https:\\\/\\\/mawelodges.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-Mawe-logo-3-300x117-1.png\",\"width\":300,\"height\":117,\"caption\":\"Mawe Lodges\"},\"image\":{\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Mawe-Lodges\\\/100066949615500\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mawelodges\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/#\\\/schema\\\/person\\\/3dfe00c0df5a7702e1d858a793499af4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/mawelodges.com\"],\"url\":\"https:\\\/\\\/mawelodges.com\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lycaons dans le parc national de Tarangire - Mawe Lodges","description":"Un safari en Tanzanie vous permet d\u2019observer les lycaons \u00e0 Tarangire, o\u00f9 ils sont pr\u00e9sents. Les lycaons vivent toujours en meutes pouvant compter jusqu\u2019\u00e0 60 individus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/","og_locale":"fr_FR","og_type":"article","og_title":"Lycaons dans le parc national de Tarangire","og_description":"Un safari en Tanzanie vous permet d\u2019observer les lycaons \u00e0 Tarangire, o\u00f9 ils sont pr\u00e9sents. Les lycaons vivent toujours en meutes pouvant compter jusqu\u2019\u00e0 60 individus.","og_url":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/","og_site_name":"Mawe Lodges","article_publisher":"https:\/\/www.facebook.com\/people\/Mawe-Lodges\/100066949615500\/","article_published_time":"2023-03-03T05:08:43+00:00","article_modified_time":"2026-05-13T11:56:30+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/#article","isPartOf":{"@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/"},"author":{"name":"admin","@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/person\/3dfe00c0df5a7702e1d858a793499af4"},"headline":"Lycaons dans le parc national de Tarangire","datePublished":"2023-03-03T05:08:43+00:00","dateModified":"2026-05-13T11:56:30+00:00","mainEntityOfPage":{"@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/"},"wordCount":615,"publisher":{"@id":"https:\/\/mawelodges.com\/fr\/#organization"},"image":{"@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/#primaryimage"},"thumbnailUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp","articleSection":["Destinations","Exp\u00e9riences et activit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/","url":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/","name":"Lycaons dans le parc national de Tarangire - Mawe Lodges","isPartOf":{"@id":"https:\/\/mawelodges.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/#primaryimage"},"image":{"@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/#primaryimage"},"thumbnailUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp","datePublished":"2023-03-03T05:08:43+00:00","dateModified":"2026-05-13T11:56:30+00:00","description":"Un safari en Tanzanie vous permet d\u2019observer les lycaons \u00e0 Tarangire, o\u00f9 ils sont pr\u00e9sents. Les lycaons vivent toujours en meutes pouvant compter jusqu\u2019\u00e0 60 individus.","breadcrumb":{"@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/#primaryimage","url":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp","contentUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/mawelodges.com\/fr\/african-wild-dogs-in-tarangire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mawelodges.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Lycaons dans le parc national de Tarangire"}]},{"@type":"WebSite","@id":"https:\/\/mawelodges.com\/fr\/#website","url":"https:\/\/mawelodges.com\/fr\/","name":"Mawe Lodges","description":"Mawe Lodges official website","publisher":{"@id":"https:\/\/mawelodges.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mawelodges.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mawelodges.com\/fr\/#organization","name":"Mawe Lodges","url":"https:\/\/mawelodges.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-Mawe-logo-3-300x117-1.png","contentUrl":"https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-Mawe-logo-3-300x117-1.png","width":300,"height":117,"caption":"Mawe Lodges"},"image":{"@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Mawe-Lodges\/100066949615500\/","https:\/\/www.instagram.com\/mawelodges\/"]},{"@type":"Person","@id":"https:\/\/mawelodges.com\/fr\/#\/schema\/person\/3dfe00c0df5a7702e1d858a793499af4","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de98eee82427a5297f7eb783a89ad2b89d815dfdbb047e58cc75929e09b0fe58?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/mawelodges.com"],"url":"https:\/\/mawelodges.com\/fr\/author\/admin\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp",640,427,false],"thumbnail":["https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire-150x150.webp",150,150,true],"medium":["https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire-300x200.webp",300,200,true],"medium_large":["https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp",640,427,false],"large":["https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp",640,427,false],"1536x1536":["https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp",640,427,false],"2048x2048":["https:\/\/mawelodges.com\/wp-content\/uploads\/2023\/10\/wild-dogs-in-tarangire.webp",640,427,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/mawelodges.com\/fr\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Lycaons dans le parc national de Tarangire : le joyau cach\u00e9 de la faune tanzanienne D\u00e9couvrez les lycaons \u00e0 Tarangire Le parc national de Tarangire est un joyau cach\u00e9, r\u00e9put\u00e9 pour sa faune vari\u00e9e et abondante, au c\u0153ur du circuit safari du nord de la Tanzanie. Parmi les habitants embl\u00e9matiques du parc, le lycaon africain,...","_links":{"self":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts\/26957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/comments?post=26957"}],"version-history":[{"count":3,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts\/26957\/revisions"}],"predecessor-version":[{"id":30083,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/posts\/26957\/revisions\/30083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/media\/26958"}],"wp:attachment":[{"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/media?parent=26957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/categories?post=26957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mawelodges.com\/fr\/wp-json\/wp\/v2\/tags?post=26957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}